{"id":133550,"date":"2024-10-21T23:30:00","date_gmt":"2024-10-21T21:30:00","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=133550"},"modified":"2024-10-22T13:27:41","modified_gmt":"2024-10-22T11:27:41","slug":"las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/","title":{"rendered":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n"},"content":{"rendered":"\n<p>Este lunes se celebr\u00f3 en el Hotel de la Real Colegiata de San Isidoro de Le\u00f3n la <strong>presentaci\u00f3n de las cuadrag\u00e9simas Jornadas Gastron\u00f3micas del Bierzo<\/strong>, un evento que este a\u00f1o llega cargado de novedades. La jornada cont\u00f3 con una <strong>amplia representaci\u00f3n institucional<\/strong>, destacando la presencia del alcalde de Le\u00f3n, Jos\u00e9 Antonio Diez, la alcaldesa de San Andr\u00e9s del Rabanedo, Ana Mar\u00eda Fern\u00e1ndez, el delegado territorial de la Junta, Eduardo Diego, el subdelegado del Gobierno en Le\u00f3n, H\u00e9ctor Alaiz, el diputado provincial Jos\u00e9 Pelliteiro y los procuradores Diego Moreno y Yolanda Sacrist\u00e1n.<\/p>\n\n\n\n<p>Por parte del <strong>Bierzo<\/strong>, asistieron la vicerrectora del campus de Ponferrada, Pilar Marqu\u00e9s, el presidente del Consejo Regulador de la IGP Botillo del Bierzo, \u00d3scar Ramos, y el gerente de Alimentos de Calidad del Bierzo, Pablo Linares. Adem\u00e1s, tambi\u00e9n estuvo presente una delegaci\u00f3n del Consejo Comarcal del Bierzo encabezada por su presidente, Olegario Ram\u00f3n, y las consejeras Cristina P\u00e9rez y Laura Fern\u00e1ndez, junto con los consejeros Jos\u00e9 Antonio Pereira, Jorge Blanco, Pedro Jorge Fuertes y Luis Perales.<\/p>\n\n\n\n<p>El acto fue inaugurado por Jos\u00e9 Ca\u00f1edo, presidente de la <strong>Academia Leonesa de Gastronom\u00eda<\/strong>, quien destac\u00f3 la importancia de este evento para la promoci\u00f3n de los productos bercianos. Ca\u00f1edo se\u00f1al\u00f3 que en esta edici\u00f3n participan 25 restaurantes del Bierzo y 12 bodegas de la D.O. Bierzo, que ofrecer\u00e1n catas y experiencias de enoturismo. \u201cAnimamos a todos los leoneses a visitar el Bierzo y disfrutar de sus productos, como el botillo, las cerezas, la pera conferencia, las manzanas reineta, las casta\u00f1as y los pimientos asados, todos ellos de alta calidad\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Por su parte, el alcalde de Le\u00f3n,<strong> Jos\u00e9 Antonio Diez<\/strong>, agradeci\u00f3 al Consejo Comarcal del Bierzo por presentar este evento en la capital leonesa y subray\u00f3 la estrecha relaci\u00f3n entre Le\u00f3n y El Bierzo, indicando que \u201cLe\u00f3n no se puede entender sin el Bierzo\u201d. Invit\u00f3 a los ciudadanos a conocer los productos bercianos y destac\u00f3 la importancia de promocionar estos productos tanto a nivel local como nacional.<\/p>\n\n\n\n<p>El presidente del Consejo Comarcal del Bierzo,<strong> Olegario Ram\u00f3n<\/strong>, resalt\u00f3 la consolidaci\u00f3n de las Jornadas Gastron\u00f3micas, que cumplen 40 a\u00f1os, e inform\u00f3 de las novedades como la participaci\u00f3n de restaurantes de fuera de la comarca, incluyendo uno en Madrid, y la organizaci\u00f3n de catas en 12 bodegas de la D.O. Bierzo. Ram\u00f3n hizo un llamamiento para que restaurantes de Le\u00f3n y su provincia se sumen en futuras ediciones y reiter\u00f3 que \u201cel Manzanal debe ser un puerto que nos una, no que nos separe\u201d.<\/p>\n\n\n\n<p>Para finalizar, los asistentes disfrutaron de una degustaci\u00f3n preparada por el chef del <strong>Hotel de la Real Colegiata<\/strong> <strong>de San Isidoro<\/strong>, con productos t\u00edpicos del Bierzo.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"133553\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion5-1024x768.jpeg\" alt=\"\" class=\"wp-image-133553\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion5-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion5-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"133555\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion3-1024x768.jpeg\" alt=\"\" class=\"wp-image-133555\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion3-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion3-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"133551\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion6-1024x768.jpeg\" alt=\"\" class=\"wp-image-133551\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion6-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion6-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"133557\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion2-1024x768.jpeg\" alt=\"\" class=\"wp-image-133557\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion2-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacion2-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"133559\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1-1024x768.jpeg\" alt=\"\" class=\"wp-image-133559\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Consejo, el alcalde de Le\u00f3n y el presidente de la Academia Leonesa de Gastronom\u00eda inauguraron el acto de presentaci\u00f3n, celebrado en el Hotel Real Colegiata de San Isidoro. <\/p>\n","protected":false},"author":3,"featured_media":133559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[363],"class_list":["post-133550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-leon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"El presidente del Consejo, el alcalde de Le\u00f3n y el presidente de la Academia Leonesa de Gastronom\u00eda inauguraron el acto de presentaci\u00f3n, celebrado en el Hotel Real Colegiata de San Isidoro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-21T21:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T11:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n\",\"datePublished\":\"2024-10-21T21:30:00+00:00\",\"dateModified\":\"2024-10-22T11:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/\"},\"wordCount\":486,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/presentacionleon1.jpeg\",\"keywords\":[\"Le\u00f3n\"],\"articleSection\":[\"Turismo\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/\",\"name\":\"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/presentacionleon1.jpeg\",\"datePublished\":\"2024-10-21T21:30:00+00:00\",\"dateModified\":\"2024-10-22T11:27:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/presentacionleon1.jpeg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/presentacionleon1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/","og_locale":"gl_ES","og_type":"article","og_title":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo","og_description":"El presidente del Consejo, el alcalde de Le\u00f3n y el presidente de la Academia Leonesa de Gastronom\u00eda inauguraron el acto de presentaci\u00f3n, celebrado en el Hotel Real Colegiata de San Isidoro.","og_url":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2024-10-21T21:30:00+00:00","article_modified_time":"2024-10-22T11:27:41+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n","datePublished":"2024-10-21T21:30:00+00:00","dateModified":"2024-10-22T11:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/"},"wordCount":486,"image":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg","keywords":["Le\u00f3n"],"articleSection":["Turismo"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/","url":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/","name":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg","datePublished":"2024-10-21T21:30:00+00:00","dateModified":"2024-10-22T11:27:41+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/10\/presentacionleon1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/las-xl-jornadas-gastronomicas-del-bierzo-triunfan-en-leon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Las XL Jornadas Gastron\u00f3micas del Bierzo triunfan en Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=133550"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/133559"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=133550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=133550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=133550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}