{"id":133413,"date":"2024-09-20T12:36:11","date_gmt":"2024-09-20T10:36:11","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=133413"},"modified":"2024-09-20T12:40:17","modified_gmt":"2024-09-20T10:40:17","slug":"el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/","title":{"rendered":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente"},"content":{"rendered":"\n<p>El presidente del Consejo Comarcal del Bierzo, Olegario Ram\u00f3n, se desplaz\u00f3 este viernes a Le\u00f3n para mantener una reuni\u00f3n de trabajo con el consejero de Medio Ambiente de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez-Qui\u00f1ones. El objetivo principal del <strong>encuentro fue solicitar una mejora del decreto de 2005 que regula la cesi\u00f3n de competencias en materia de brigadas contra incendios<\/strong>, con el fin de garantizar una financiaci\u00f3n que permita a las brigadas trabajar durante nueve meses en la comarca del Bierzo.<\/p>\n\n\n\n<p>Ram\u00f3n estuvo acompa\u00f1ado por la consejera de Relaciones Institucionales, Susana Folla, y el t\u00e9cnico de Medio Ambiente del Consejo, \u00d3scar Franc\u00e9s. La delegaci\u00f3n comarcal plante\u00f3 la necesidad de que <strong>los seis trabajadores fijos discontinuos de las brigadas antiincendios del Bierzo puedan estar empleados durante todo el a\u00f1o<\/strong>, con el objetivo de fortalecer la prevenci\u00f3n y respuesta ante incendios forestales en la zona.<\/p>\n\n\n\n<p>Otro de los temas tratados durante la reuni\u00f3n fue la situaci\u00f3n del <strong>servicio de Protecci\u00f3n Civil del Bierzo<\/strong>, para el cual se solicit\u00f3 la entrega de un veh\u00edculo que est\u00e1 pendiente, as\u00ed como una mejora en el convenio que permita la renovaci\u00f3n del vestuario de los voluntarios que prestan servicio en la agrupaci\u00f3n comarcal.<\/p>\n\n\n\n<p>&#8220;Ha sido una reuni\u00f3n cordial, en la que <strong>hemos visto receptividad por parte del consejero<\/strong>. Creemos que esto tendr\u00e1 repercusi\u00f3n en las decisiones que se tomen en la Junta, en la l\u00ednea de prestar un mejor servicio, que es lo que queremos&#8221;, afirm\u00f3 Olegario Ram\u00f3n al finalizar el encuentro.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1-1024x768.jpeg\" alt=\"\" class=\"wp-image-133416\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El presidente y la consejera comarcal de Relaciones Institucionales se desplazaron este viernes a Le\u00f3n para mantener una reuni\u00f3n de trabajo con el consejero de Medio Ambiente de la Junta de Castilla y Le\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":133416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[363],"class_list":["post-133413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-leon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"El presidente y la consejera comarcal de Relaciones Institucionales se desplazaron este viernes a Le\u00f3n para mantener una reuni\u00f3n de trabajo con el consejero de Medio Ambiente de la Junta de Castilla y Le\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T10:36:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T10:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente\",\"datePublished\":\"2024-09-20T10:36:11+00:00\",\"dateModified\":\"2024-09-20T10:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/\"},\"wordCount\":292,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MedioAmbiente1.jpeg\",\"keywords\":[\"Le\u00f3n\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/\",\"name\":\"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MedioAmbiente1.jpeg\",\"datePublished\":\"2024-09-20T10:36:11+00:00\",\"dateModified\":\"2024-09-20T10:40:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MedioAmbiente1.jpeg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MedioAmbiente1.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/","og_locale":"gl_ES","og_type":"article","og_title":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo","og_description":"El presidente y la consejera comarcal de Relaciones Institucionales se desplazaron este viernes a Le\u00f3n para mantener una reuni\u00f3n de trabajo con el consejero de Medio Ambiente de la Junta de Castilla y Le\u00f3n.","og_url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2024-09-20T10:36:11+00:00","article_modified_time":"2024-09-20T10:40:17+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente","datePublished":"2024-09-20T10:36:11+00:00","dateModified":"2024-09-20T10:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/"},"wordCount":292,"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg","keywords":["Le\u00f3n"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/","url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/","name":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg","datePublished":"2024-09-20T10:36:11+00:00","dateModified":"2024-09-20T10:40:17+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/MedioAmbiente1.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-solicita-la-mejora-del-decreto-que-regula-la-cesion-de-competencias-en-materia-de-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El Consejo Comarcal solicita la mejora del decreto que regula la cesi\u00f3n de competencias en materia de Medio Ambiente"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=133413"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/133416"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=133413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=133413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=133413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}