{"id":133362,"date":"2024-09-13T12:05:26","date_gmt":"2024-09-13T10:05:26","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=133362"},"modified":"2024-09-13T12:05:28","modified_gmt":"2024-09-13T10:05:28","slug":"el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/","title":{"rendered":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo"},"content":{"rendered":"\n<p>El Consejo Comarcal del Bierzo, encabezado por su presidente, Olegario Ram\u00f3n, ha decidido tomar <strong>medidas para solucionar la grave situaci\u00f3n que atraviesa el servicio de Oncolog\u00eda<\/strong> del Hospital El Bierzo, donde la falta de especialistas est\u00e1 obligando a facultativos de Medicina Interna a atender a los pacientes oncol\u00f3gicos.<\/p>\n\n\n\n<p>Este mismo viernes, la Consejer\u00eda de Sanidad solicit\u00f3 una reuni\u00f3n urgente con el presidente del Consejo Comarcal para abordar esta problem\u00e1tica. Olegario Ram\u00f3n aprovechar\u00e1 su viaje a Valladolid el lunes, donde tiene prevista una reuni\u00f3n con el consejero de Cultura, Turismo y Deporte, para encontrarse tambi\u00e9n con el responsable de Sanidad, Alejandro V\u00e1zquez, y tratar la cr\u00edtica situaci\u00f3n de manera directa.<\/p>\n\n\n\n<p>Antes de recibir la llamada de la Consejer\u00eda, el presidente del Consejo ya hab\u00eda decidido <strong>liderar una iniciativa<\/strong> para solicitar, con el <strong>apoyo de los alcaldes y alcaldesas del Bierzo<\/strong>, una soluci\u00f3n definitiva y estructural a la falta de especialistas en Oncolog\u00eda. Esta propuesta se formalizar\u00e1 mediante un escrito dirigido a las Consejer\u00eda de Sanidad de la Junta de Castilla y Le\u00f3n, reclamando la cobertura de las cuatro plazas vacantes de onc\u00f3logos e incluso el incremento de la plantilla con una quinta plaza.<\/p>\n\n\n\n<p>Olegario Ram\u00f3n subray\u00f3 que la situaci\u00f3n es dram\u00e1tica para los pacientes oncol\u00f3gicos y sus familias, con quienes ha mantenido conversaciones en las \u00faltimas semanas. &#8220;Esto no es una cuesti\u00f3n pol\u00edtica ni un ataque contra ning\u00fan partido. No es la politizaci\u00f3n de la Sanidad, sino una demanda urgente para garantizar un <strong>servicio adecuado y estable<\/strong> que atienda las necesidades de los pacientes&#8221;, destac\u00f3.<\/p>\n\n\n\n<p>El presidente del Consejo compareci\u00f3 ante los medios acompa\u00f1ado por la vicepresidenta del Consejo Comarcal, <strong>Lorena Fern\u00e1ndez<\/strong>, y la consejera de Relaciones Institucionales, <strong>Susana Folla<\/strong>, adem\u00e1s de otros consejeros y consejeras comarcales que asistieron a la convocatoria.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-1024x768.jpeg\" alt=\"\" class=\"wp-image-133363\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este mismo viernes, la Consejer\u00eda de Sanidad solicit\u00f3 una reuni\u00f3n urgente con el presidente del Consejo Comarcal para abordar esta problem\u00e1tica. <\/p>\n","protected":false},"author":3,"featured_media":133363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[294],"class_list":["post-133362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-ponferrada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"Este mismo viernes, la Consejer\u00eda de Sanidad solicit\u00f3 una reuni\u00f3n urgente con el presidente del Consejo Comarcal para abordar esta problem\u00e1tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T10:05:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T10:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1919\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo\",\"datePublished\":\"2024-09-13T10:05:26+00:00\",\"dateModified\":\"2024-09-13T10:05:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/\"},\"wordCount\":344,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg\",\"keywords\":[\"Ponferrada\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/\",\"name\":\"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg\",\"datePublished\":\"2024-09-13T10:05:26+00:00\",\"dateModified\":\"2024-09-13T10:05:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg\",\"width\":2560,\"height\":1919},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/","og_locale":"gl_ES","og_type":"article","og_title":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo","og_description":"Este mismo viernes, la Consejer\u00eda de Sanidad solicit\u00f3 una reuni\u00f3n urgente con el presidente del Consejo Comarcal para abordar esta problem\u00e1tica.","og_url":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2024-09-13T10:05:26+00:00","article_modified_time":"2024-09-13T10:05:28+00:00","og_image":[{"width":2560,"height":1919,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo","datePublished":"2024-09-13T10:05:26+00:00","dateModified":"2024-09-13T10:05:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/"},"wordCount":344,"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg","keywords":["Ponferrada"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/","url":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/","name":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg","datePublished":"2024-09-13T10:05:26+00:00","dateModified":"2024-09-13T10:05:28+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/09\/RP-Consejo-Comarcal-del-Bierzo-scaled.jpeg","width":2560,"height":1919},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-consejo-reclamara-una-solucion-urgente-y-estable-ante-la-falta-de-especialistas-en-oncologia-en-el-hospital-el-bierzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El Consejo reclamar\u00e1 una soluci\u00f3n urgente y estable ante la falta de especialistas en Oncolog\u00eda en el Hospital El Bierzo"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=133362"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/133362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/133363"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=133362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=133362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=133362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}