{"id":132088,"date":"2024-02-06T14:21:06","date_gmt":"2024-02-06T13:21:06","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=132088"},"modified":"2024-02-06T15:03:40","modified_gmt":"2024-02-06T14:03:40","slug":"el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/","title":{"rendered":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar"},"content":{"rendered":"\n<p>El presidente del Consejo Comarcal, Olegario Ram\u00f3n, realiz\u00f3 estas declaraciones en el transcurso de la<strong> visita institucional al Ayuntamiento de Torre del Bierzo<\/strong>, donde fue recibido por el alcalde, Gabriel Folgado, miembros de la corporaci\u00f3n municipal y presidentes de las juntas vecinales del municipio. El objetivo del encuentro es el de informar de los servicios menos conocidos que la instituci\u00f3n presta a entidades locales y ciudadan\u00eda, as\u00ed como conocer de primera mano los problemas y necesidades de los municipios.<\/p>\n\n\n\n<p>Durante el encuentro, el presidente inform\u00f3 a la corporaci\u00f3n municipal de Torre del Bierzo sobre los avances positivos derivados de la reciente reuni\u00f3n en el Ayuntamiento de Ponferrada, donde se habl\u00f3 sobre la <strong>cesi\u00f3n de un solar para la construcci\u00f3n de una sede permanente y propia para la instituci\u00f3n comarcal<\/strong>. Olegario Ram\u00f3n record\u00f3 que el convenio marco firmado con la Junta establece que la Administraci\u00f3n regional financiar\u00eda la redacci\u00f3n del proyecto, siempre y cuando se concrete la cesi\u00f3n del terreno por parte del Ayuntamiento. &#8220;Yo creo que, si hay solar, habr\u00e1 compromiso de la Junta para construir esa sede propia y digna que preste mejor servicio a la ciudadan\u00eda&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p>El alcalde de Torre del Bierzo, Gabriel Folgado, expres\u00f3 su agradecimiento por la visita y solicit\u00f3 la colaboraci\u00f3n del Consejo Comarcal en la <strong>promoci\u00f3n tur\u00edstica del municipio<\/strong>, haciendo especial hincapi\u00e9 en los Cortines de Fonfr\u00eda, reconocidos como Bien de Inter\u00e9s Tur\u00edstico Cultural. Asimismo, el alcalde y los representantes de las juntas vecinales plantearon la necesidad de adelantar los fondos del Plan de Peque\u00f1as Obras, con el fin de garantizar el pago a las empresas encargadas de ejecutar los trabajos, medida que resulta fundamental para el desarrollo de proyectos locales.<\/p>\n\n\n\n<p>La visita cont\u00f3 con la presencia de<strong> la vicepresidenta, Lorena Fern\u00e1ndez; el portavoz del PP, Jos\u00e9 Manuel Pereira; as\u00ed como los consejeros y consejeras Andr\u00e9s Arias (PSOE), Cristina P\u00e9rez (PSOE), Jorge Blanco (PP) y Ra\u00fal Fern\u00e1ndez (PP)<\/strong>. La pr\u00f3xima visita de la delegaci\u00f3n comarcal ser\u00e1 a Carracedelo el 14 de febrero.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"132095\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo4-1024x768.jpg\" alt=\"\" class=\"wp-image-132095\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo4-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo4-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"132093\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo3-1024x768.jpg\" alt=\"\" class=\"wp-image-132093\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo3-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo3-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"132091\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo2-1024x768.jpg\" alt=\"\" class=\"wp-image-132091\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo2-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo2-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"132089\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1-1024x768.jpg\" alt=\"\" class=\"wp-image-132089\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Olegario Ram\u00f3n realiz\u00f3 estas declaraciones en el transcurso de la visita institucional al Ayuntamiento de Torre del Bierzo, donde fue recibido por el alcalde, Gabriel Folgado, miembros de la corporaci\u00f3n municipal y presidentes de las juntas vecinales del municipio.<\/p>\n","protected":false},"author":3,"featured_media":132089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[263],"class_list":["post-132088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-torre-del-bierzo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"Olegario Ram\u00f3n realiz\u00f3 estas declaraciones en el transcurso de la visita institucional al Ayuntamiento de Torre del Bierzo, donde fue recibido por el alcalde, Gabriel Folgado, miembros de la corporaci\u00f3n municipal y presidentes de las juntas vecinales del municipio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T13:21:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T14:03:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar\",\"datePublished\":\"2024-02-06T13:21:06+00:00\",\"dateModified\":\"2024-02-06T14:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/\"},\"wordCount\":383,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/torredelbierzo1.jpg\",\"keywords\":[\"Torre del Bierzo\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/\",\"name\":\"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/torredelbierzo1.jpg\",\"datePublished\":\"2024-02-06T13:21:06+00:00\",\"dateModified\":\"2024-02-06T14:03:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/torredelbierzo1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/torredelbierzo1.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/","og_locale":"gl_ES","og_type":"article","og_title":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo","og_description":"Olegario Ram\u00f3n realiz\u00f3 estas declaraciones en el transcurso de la visita institucional al Ayuntamiento de Torre del Bierzo, donde fue recibido por el alcalde, Gabriel Folgado, miembros de la corporaci\u00f3n municipal y presidentes de las juntas vecinales del municipio.","og_url":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2024-02-06T13:21:06+00:00","article_modified_time":"2024-02-06T14:03:40+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar","datePublished":"2024-02-06T13:21:06+00:00","dateModified":"2024-02-06T14:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/"},"wordCount":383,"image":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg","keywords":["Torre del Bierzo"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/","url":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/","name":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg","datePublished":"2024-02-06T13:21:06+00:00","dateModified":"2024-02-06T14:03:40+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2024\/02\/torredelbierzo1.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-presidente-del-consejo-confia-en-que-la-junta-financie-la-construccion-de-la-nueva-sede-si-el-ayuntamiento-de-ponferrada-cede-un-solar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El presidente del Consejo conf\u00eda en que la Junta financie la construcci\u00f3n de la nueva sede si el Ayuntamiento de Ponferrada cede un solar"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/132088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=132088"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/132088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/132089"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=132088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=132088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=132088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}