{"id":131838,"date":"2023-11-17T14:04:29","date_gmt":"2023-11-17T13:04:29","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=131838"},"modified":"2023-11-17T14:04:31","modified_gmt":"2023-11-17T13:04:31","slug":"el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/","title":{"rendered":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo"},"content":{"rendered":"\n<p>El estand del <strong>Consorcio Provincial de Turismo<\/strong> en la Feria de Vallodolid acogi\u00f3 este viernes la presentaci\u00f3n de la oferta tur\u00edstica de El Bierzo. El presidente del Consejo Comarcal, Olegario Ram\u00f3n, fue el encargado de dirigir el acto, que congreg\u00f3 a numeroso p\u00fablico y a una amplia representaci\u00f3n berciana. Tambi\u00e9n asistieron el consejero de Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio, Juan Carlos Su\u00e1rez Qui\u00f1ones; el presidente de la Diputaci\u00f3n de Le\u00f3n, Gerardo \u00c1lvarez Courel, y el delegado territorial de la Junta de Castilla y Le\u00f3n, Eduardo Diego.<\/p>\n\n\n\n<p>La alcaldesa de Peranzanes, Henar Garc\u00eda, fue la primera en intervenir para presentar la producci\u00f3n audiovisual <strong>&#8220;Tradici\u00f3n y danzas del Valle de Fornela&#8221;<\/strong>. El v\u00eddeo se grab\u00f3 el pasado verano y ofrece im\u00e1genes de las tradicionales danzas de Fornela. El Ayuntamiento, tal y como explic\u00f3 la regidora, pretende obtener el reconocimiento como Fiesta de Inter\u00e9s Tur\u00edstico Regional para la Romer\u00eda de Trascastro, un t\u00edtulo al que se ha optado en otras ocasiones sin \u00e9xito. El presidente del Consejo expres\u00f3 su apoyo y se mostr\u00f3 esperanzado de que la Junta \u201creconozca como se merece el gran valor de estas danzas centenarias y el atractivo tur\u00edstico que representan para El Bierzo\u201d.<\/p>\n\n\n\n<p>Posteriormente, Olegario Ram\u00f3n present\u00f3 la iniciativa <strong><a href=\"https:\/\/youtu.be\/nfqL6Vz9504?si=csb_HjwfTdGn_fsY\">\u201c800 Tseras\u201d<\/a><\/strong>, un trazado para deportistas de alto nivel que discurre por los municipios de P\u00e1ramo del Sil, Palacios del Sil e Ig\u00fce\u00f1a. El Consejo Comarcal inici\u00f3 el proyecto hace dos a\u00f1os y cont\u00f3 con la colaboraci\u00f3n del atleta ol\u00edmpico y plusmarquista berciano Sa\u00fal Ord\u00f3\u00f1ez, que se encarg\u00f3 del dise\u00f1o del itinerario. El deportista, que suele entrenar en la zona, habl\u00f3 en el acto sobre la experiencia \u00fanica y los impresionantes paisajes que ofrece este trazado. <\/p>\n\n\n\n<p>El acto concluy\u00f3 con la presentaci\u00f3n de la <strong><a href=\"https:\/\/youtu.be\/DLb1tFjYmxo?si=bt51YN0BcW3DSCWM\">marca territorio EL BIERZO<\/a><\/strong>. Con el lema &#8220;Yo soy de El Bierzo&#8221;, Olegario Ram\u00f3n explic\u00f3 que la campa\u00f1a para dar a conocer esta nueva identidad visual \u201cbusca fortalecer el sentimiento de pertenencia y convertir a la marca en un s\u00edmbolo visual para atraer talento, inversiones y turismo\u201d. El dise\u00f1ador Juan Orive explic\u00f3 que la tipograf\u00eda, creada exclusivamente para esta ocasi\u00f3n, \u201crepresenta solidez, ancestralidad, naturaleza, miner\u00eda y ecolog\u00eda, formando la identidad \u00fanica de El Bierzo. Al mismo tiempo es una tipograf\u00eda joven y din\u00e1mica, capturando la diversidad de ideas con la forma de la tipograf\u00eda y los colores de la bandera de la comarca\u201d.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131841\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur2-1024x683.jpg\" alt=\"\" class=\"wp-image-131841\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur2-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur2-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131851\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur7-1024x683.jpg\" alt=\"\" class=\"wp-image-131851\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur7-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur7-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131843\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur3-1024x683.jpg\" alt=\"\" class=\"wp-image-131843\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur3-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur3-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131853\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur8-1024x683.jpg\" alt=\"\" class=\"wp-image-131853\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur8-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur8-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131849\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur6-1024x683.jpg\" alt=\"\" class=\"wp-image-131849\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur6-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur6-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131855\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur9-1024x683.jpg\" alt=\"\" class=\"wp-image-131855\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur9-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur9-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131839\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1-1024x683.jpg\" alt=\"\" class=\"wp-image-131839\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131845\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur4-1024x683.jpg\" alt=\"\" class=\"wp-image-131845\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur4-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur4-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"131857\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur10-1024x683.jpg\" alt=\"\" class=\"wp-image-131857\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur10-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur10-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"131859\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur11-1024x576.jpg\" alt=\"\" class=\"wp-image-131859\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur11-980x551.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur11-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El acto de presentaci\u00f3n de la oferta tur\u00edstica de la comarca congreg\u00f3 a numeroso p\u00fablico y representantes intitucionales.<\/p>\n","protected":false},"author":3,"featured_media":131839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[196],"class_list":["post-131838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-intur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"El acto de presentaci\u00f3n de la oferta tur\u00edstica de la comarca congreg\u00f3 a numeroso p\u00fablico y representantes intitucionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-17T13:04:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T13:04:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo\",\"datePublished\":\"2023-11-17T13:04:29+00:00\",\"dateModified\":\"2023-11-17T13:04:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/\"},\"wordCount\":456,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur1.jpg\",\"keywords\":[\"Intur\"],\"articleSection\":[\"Turismo\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/\",\"name\":\"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur1.jpg\",\"datePublished\":\"2023-11-17T13:04:29+00:00\",\"dateModified\":\"2023-11-17T13:04:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/","og_locale":"gl_ES","og_type":"article","og_title":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo","og_description":"El acto de presentaci\u00f3n de la oferta tur\u00edstica de la comarca congreg\u00f3 a numeroso p\u00fablico y representantes intitucionales.","og_url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2023-11-17T13:04:29+00:00","article_modified_time":"2023-11-17T13:04:31+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo","datePublished":"2023-11-17T13:04:29+00:00","dateModified":"2023-11-17T13:04:31+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/"},"wordCount":456,"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg","keywords":["Intur"],"articleSection":["Turismo"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/","url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/","name":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg","datePublished":"2023-11-17T13:04:29+00:00","dateModified":"2023-11-17T13:04:31+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-presenta-en-intur-una-propuesta-que-resalta-la-tradicion-la-riqueza-natural-y-el-desarrollo-sostenible-de-el-bierzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El Consejo Comarcal presenta en Intur una propuesta que resalta la tradici\u00f3n, la riqueza natural y el desarrollo sostenible de El Bierzo"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=131838"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/131839"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=131838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=131838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=131838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}