{"id":131266,"date":"2023-08-14T11:56:53","date_gmt":"2023-08-14T09:56:53","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=131266"},"modified":"2023-08-16T09:49:37","modified_gmt":"2023-08-16T07:49:37","slug":"puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/","title":{"rendered":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#8216;Apostando por El Bierzo&#8217;"},"content":{"rendered":"\n<p>La consejera comarcal de Formaci\u00f3n y Empleo, Laura Fern\u00e1ndez, y el alcalde, Julio Arias, recorrieron por la tarde los puestos, entre los que destacaban<strong> dos bodegas, dos productores de miel y una f\u00e1brica de embutidos del municipio<\/strong>. El regidor destac\u00f3 el crecimiento de los sectores tur\u00edstico y agroalimentario en la localidad: \u201cLo m\u00e1s importante son los vinos, pero tenemos muchos productores de miel; la gente ve futuro en ello y s\u00ed que se est\u00e1n desarrollando\u201d.<\/p>\n\n\n\n<p>La consejera Laura Fern\u00e1ndez se mostr\u00f3 satisfecha por el \u00e9xito de la feria en Puente de Domingo Fl\u00f3rez, donde en poco tiempo se vendieron los vales que la organizaci\u00f3n pone a la venta a dos euros con cincuenta c\u00e9ntimos para canjear por compras de cinco euros. \u201cGracias a estas ferias tenemos una gran <strong>oportunidad para conocer los productos locales que tenemos en El Bierzo<\/strong> porque, a veces, no son conocidos (\u2026); tambi\u00e9n para apoyar a los productores locales y contribuir al desarrollo de la comarca\u201d, resalt\u00f3.<\/p>\n\n\n\n<p>El Banco de Tierras del Consejo Comarcal organiza estas ferias en colaboraci\u00f3n con Alimentos de Calidad del Bierzo, Asociaci\u00f3n Berciana de Agricultores y los ayuntamientos participantes. La pr\u00f3xima cita ser\u00e1 el <strong>domingo 20 de agosto en Cueto<\/strong>, localidad perteneciente al municipio de Sancedo.<\/p>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"825\" data-id=\"131267\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1024x825.jpg\" alt=\"\" class=\"wp-image-131267\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-980x789.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-480x387.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131269\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-1024x768.jpg\" alt=\"\" class=\"wp-image-131269\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131271\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente3-1024x768.jpg\" alt=\"\" class=\"wp-image-131271\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente3-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente3-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131273\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202249-1024x768.jpg\" alt=\"\" class=\"wp-image-131273\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202249-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202249-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131275\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202320-1024x768.jpg\" alt=\"\" class=\"wp-image-131275\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202320-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202320-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131277\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202519-1024x768.jpg\" alt=\"\" class=\"wp-image-131277\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202519-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_202519-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131279\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203401-1024x768.jpg\" alt=\"\" class=\"wp-image-131279\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203401-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203401-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131281\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203708-1024x768.jpg\" alt=\"\" class=\"wp-image-131281\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203708-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_203708-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131283\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_204544-1024x768.jpg\" alt=\"\" class=\"wp-image-131283\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_204544-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_204544-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131285\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_205456-1024x768.jpg\" alt=\"\" class=\"wp-image-131285\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_205456-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/IMG_20230813_205456-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"825\" data-id=\"131287\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-1024x825.jpg\" alt=\"\" class=\"wp-image-131287\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-980x789.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-480x387.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131289\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-1-1024x768.jpg\" alt=\"\" class=\"wp-image-131289\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-1-980x735.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente2-1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La consejera comarcal de Formaci\u00f3n y Empleo y el alcalde recorrieron por la tarde los puestos, entre los que destacaban dos bodegas, dos productores de miel y una f\u00e1brica de embutidos del municipio.<\/p>\n","protected":false},"author":3,"featured_media":131287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-131266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#039;Apostando por El Bierzo&#039; - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#039;Apostando por El Bierzo&#039; - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"La consejera comarcal de Formaci\u00f3n y Empleo y el alcalde recorrieron por la tarde los puestos, entre los que destacaban dos bodegas, dos productores de miel y una f\u00e1brica de embutidos del municipio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-14T09:56:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T07:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2062\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#8216;Apostando por El Bierzo&#8217;\",\"datePublished\":\"2023-08-14T09:56:53+00:00\",\"dateModified\":\"2023-08-16T07:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/\"},\"wordCount\":229,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feria-puente1-1-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/\",\"name\":\"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria 'Apostando por El Bierzo' - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feria-puente1-1-scaled.jpg\",\"datePublished\":\"2023-08-14T09:56:53+00:00\",\"dateModified\":\"2023-08-16T07:49:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feria-puente1-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feria-puente1-1-scaled.jpg\",\"width\":2560,\"height\":2062},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#8216;Apostando por El Bierzo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria 'Apostando por El Bierzo' - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/","og_locale":"gl_ES","og_type":"article","og_title":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria 'Apostando por El Bierzo' - Consejo Comarcal del Bierzo","og_description":"La consejera comarcal de Formaci\u00f3n y Empleo y el alcalde recorrieron por la tarde los puestos, entre los que destacaban dos bodegas, dos productores de miel y una f\u00e1brica de embutidos del municipio.","og_url":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2023-08-14T09:56:53+00:00","article_modified_time":"2023-08-16T07:49:37+00:00","og_image":[{"width":2560,"height":2062,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#8216;Apostando por El Bierzo&#8217;","datePublished":"2023-08-14T09:56:53+00:00","dateModified":"2023-08-16T07:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/"},"wordCount":229,"image":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/","url":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/","name":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria 'Apostando por El Bierzo' - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg","datePublished":"2023-08-14T09:56:53+00:00","dateModified":"2023-08-16T07:49:37+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/08\/feria-puente1-1-scaled.jpg","width":2560,"height":2062},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/puente-de-domingo-florez-acogio-ayer-la-segunda-feria-apostando-por-el-bierzo-del-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Puente de Domingo Fl\u00f3rez acogi\u00f3 la segunda feria &#8216;Apostando por El Bierzo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=131266"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/131287"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=131266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=131266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=131266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}