{"id":131121,"date":"2023-06-14T12:53:39","date_gmt":"2023-06-14T10:53:39","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=131121"},"modified":"2023-06-14T12:53:43","modified_gmt":"2023-06-14T10:53:43","slug":"el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/","title":{"rendered":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023"},"content":{"rendered":"\n<p>La sesi\u00f3n de car\u00e1cter extraordinaria tuvo como \u00fanico punto del orden del d\u00eda la aprobaci\u00f3n de actas anteriores. Posteriormente los portavoces y el presidente tomaron la palabra para <strong>despedir estos cuatro a\u00f1os<\/strong>, marcados en buena medida por la pandemia y para confirmar la buena sinton\u00eda que ha primado entre todos los miembros de la corporaci\u00f3n, &#8216;a pesar de las rencillas pol\u00edticas puntuales&#8217;, seg\u00fan se\u00f1al\u00f3 el presidente.<\/p>\n\n\n\n<p>Tres portavoces se despidieron de la instituci\u00f3n por no haber concurrido a las elecciones o no haber logrado acta de concejal. Son el <strong>consejero no adscrito Manuel de la Fuente; Ruth Morales, de Ciudadanos, y Samuel Folgueral, de USE Bierzo<\/strong>.<\/p>\n\n\n\n<p>El presidente del Consejo Comarcal. Gerardo \u00c1lvarez Courel, destac\u00f3 como dos grandes logros del mandato: la f<strong>irma del convenio marco con la Junta de Castilla y Le\u00f3n y la apertura de una oficia a pie de calle, que mejora la atenci\u00f3n ciudadana y da visibilidad al trabajo que realiza la instituci\u00f3n<\/strong>.<\/p>\n\n\n\n<p>Por \u00faltimo, hubo un recuerdo para los dos consejeros que fallecieron durante el mandato: <strong>Rafael Insunza<\/strong>, del PP, y <strong>Vicente D\u00edaz<\/strong>, del PSOE.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131128\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.01-1024x768.jpeg\" alt=\"\" class=\"wp-image-131128\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.01-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.01-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131122\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-131122\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-1-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-1-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"131124\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-1024x768.jpeg\" alt=\"\" class=\"wp-image-131124\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-980x735.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.17.03-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"131126\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48-1024x576.jpeg\" alt=\"\" class=\"wp-image-131126\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48-980x551.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48-480x270.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Pleno extraordinario 14\/06\/2023\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/sumJVWLIndc?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los portavoces de los grupos pol\u00edticos y el presidente pronunciaron un breve discurso para culminar el mandato. <\/p>\n<p>V\u00cdDEO EN LA NOTICIA<\/p>\n","protected":false},"author":3,"featured_media":131126,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[103],"class_list":["post-131121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-pleno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"Los portavoces de los grupos pol\u00edticos y el presidente pronunciaron un breve discurso para culminar el mandato.  V\u00cdDEO EN LA NOTICIA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-14T10:53:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T10:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1151\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023\",\"datePublished\":\"2023-06-14T10:53:39+00:00\",\"dateModified\":\"2023-06-14T10:53:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/\"},\"wordCount\":212,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg\",\"keywords\":[\"Pleno\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/\",\"name\":\"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg\",\"datePublished\":\"2023-06-14T10:53:39+00:00\",\"dateModified\":\"2023-06-14T10:53:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg\",\"width\":2048,\"height\":1151},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/","og_locale":"gl_ES","og_type":"article","og_title":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo","og_description":"Los portavoces de los grupos pol\u00edticos y el presidente pronunciaron un breve discurso para culminar el mandato.  V\u00cdDEO EN LA NOTICIA","og_url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2023-06-14T10:53:39+00:00","article_modified_time":"2023-06-14T10:53:43+00:00","og_image":[{"width":2048,"height":1151,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023","datePublished":"2023-06-14T10:53:39+00:00","dateModified":"2023-06-14T10:53:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/"},"wordCount":212,"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg","keywords":["Pleno"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/","url":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/","name":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023 - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg","datePublished":"2023-06-14T10:53:39+00:00","dateModified":"2023-06-14T10:53:43+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-14-at-10.29.48.jpeg","width":2048,"height":1151},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-consejo-comarcal-celebra-el-ultimo-pleno-del-mandato-2019-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El Consejo Comarcal celebra el \u00faltimo Pleno del mandato 2019-2023"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=131121"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/131121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/131126"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=131121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=131121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=131121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}