{"id":130975,"date":"2023-03-23T13:24:37","date_gmt":"2023-03-23T12:24:37","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=130975"},"modified":"2023-03-23T13:36:52","modified_gmt":"2023-03-23T12:36:52","slug":"abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/","title":{"rendered":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas"},"content":{"rendered":"\n<p>La instituci\u00f3n ha abierto el plazo de inscripci\u00f3n para los cursos incluidos dentro del Plan de Formaci\u00f3n Local 2023, que gestiona la Escuela de Administraci\u00f3n P\u00fablica de Castilla y Le\u00f3n (ECLAP) en colaboraci\u00f3n con las entidades locales.<\/p>\n\n\n\n<p>Se convocan tres acciones formativas: la primera, <strong>Actualizaci\u00f3n de Urbanismo<\/strong>, se impartir\u00e1 del 2 al 31 de mayo; la segunda, <strong>Gesti\u00f3n de Planes Antifraude y Canales de Denuncia<\/strong>, entre el 1 y el 21 de septiembre;&nbsp; y la tercera, <strong>Formando sobre Cultura del Desempe\u00f1o de Entornos Laborales<\/strong>, del 2 al 17 de octubre. Las tres se impartir\u00e1n de manera telem\u00e1tica y disponen de 50 plazas cada uno.<\/p>\n\n\n\n<p>Las personas interesadas deber\u00e1n enviar su solicitud al correo electr\u00f3nico:\u00a0 info@ccbierzo.com antes del 15 de abril. La hoja de inscripci\u00f3n est\u00e1 disponible en la <a href=\"https:\/\/ccbierzo.com\/servicios\/asistencia-municipios\/formacion\/\" target=\"_blank\" rel=\"noreferrer noopener\">web del Consejo Comarcal<\/a>.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2-1024x683.jpg\" alt=\"\" class=\"wp-image-130956\" width=\"768\" height=\"512\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las personas interesadas deber\u00e1n enviar su solicitud al correo electr\u00f3nico\u00a0 info@ccbierzo.com antes del 15 de abril. La hoja de inscripci\u00f3n est\u00e1 disponible en la web del Consejo Comarcal.<\/p>\n","protected":false},"author":3,"featured_media":130956,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[70],"class_list":["post-130975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-formacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"Las personas interesadas deber\u00e1n enviar su solicitud al correo electr\u00f3nico\u00a0 info@ccbierzo.com antes del 15 de abril. La hoja de inscripci\u00f3n est\u00e1 disponible en la web del Consejo Comarcal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-23T12:24:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-23T12:36:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas\",\"datePublished\":\"2023-03-23T12:24:37+00:00\",\"dateModified\":\"2023-03-23T12:36:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/\"},\"wordCount\":162,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/oficinas2.jpg\",\"keywords\":[\"Formaci\u00f3n\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/\",\"name\":\"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/oficinas2.jpg\",\"datePublished\":\"2023-03-23T12:24:37+00:00\",\"dateModified\":\"2023-03-23T12:36:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/oficinas2.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/oficinas2.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/","og_locale":"gl_ES","og_type":"article","og_title":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo","og_description":"Las personas interesadas deber\u00e1n enviar su solicitud al correo electr\u00f3nico\u00a0 info@ccbierzo.com antes del 15 de abril. La hoja de inscripci\u00f3n est\u00e1 disponible en la web del Consejo Comarcal.","og_url":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2023-03-23T12:24:37+00:00","article_modified_time":"2023-03-23T12:36:52+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas","datePublished":"2023-03-23T12:24:37+00:00","dateModified":"2023-03-23T12:36:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/"},"wordCount":162,"image":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg","keywords":["Formaci\u00f3n"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/","url":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/","name":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg","datePublished":"2023-03-23T12:24:37+00:00","dateModified":"2023-03-23T12:36:52+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/oficinas2.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/abierto-el-plazo-de-inscripcion-para-los-cursos-de-formacion-continua-para-personal-de-las-administraciones-publicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Abierto el plazo de inscripci\u00f3n de los cursos de formaci\u00f3n contin\u00faa para personal de las Administraciones P\u00fablicas"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=130975"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/130956"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=130975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=130975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=130975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}