{"id":130948,"date":"2023-03-17T14:19:55","date_gmt":"2023-03-17T13:19:55","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=130948"},"modified":"2023-03-17T14:22:31","modified_gmt":"2023-03-17T13:22:31","slug":"bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/","title":{"rendered":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os"},"content":{"rendered":"\n<p>Representantes de la delegaci\u00f3n de la <strong>Federaci\u00f3n de F\u00fatbol de Castilla y Le\u00f3n<\/strong> y de los tres municipios que albergar\u00e1n el torneo (Ponferrada, Bembibre y Vega de Espinareda) y el presidente de la Comarca presentaron este viernes la <strong>Liga de Debutantes 2023<\/strong>, una actividad en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os y que visten por primera vez la camiseta de sus equipos.<\/p>\n\n\n\n<p>La primera jornada se celebra este <strong>s\u00e1bado 18 de marzo en la Plaza de Santa B\u00e1rbara de Bembibre<\/strong> a partir de las 10:00 horas. Los peque\u00f1os disputar\u00e1n partidos de 20 minutos en los que no habr\u00e1 marcadores porque el objetivo es &#8220;sacar el f\u00fatbol a la calle&#8221; y que todos los ni\u00f1os y ni\u00f1as participen. <\/p>\n\n\n\n<p>Este evento precede al programa de de actividades que la Federaci\u00f3n de F\u00fatbol de Castilla y Le\u00f3n organiza con motivo de la celebraci\u00f3n de su centenario, que tendr\u00e1 lugar del 5 al 15 de abril. <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-130951\" width=\"768\" height=\"512\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Comarcal acogi\u00f3 la presentaci\u00f3n de la actividad. La capital de El Bierzo Alto ser\u00e1 el escenario de la primera jornada este s\u00e1bado 18 de marzo.<\/p>\n","protected":false},"author":3,"featured_media":130949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,19],"tags":[294],"class_list":["post-130948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","category-social","tag-ponferrada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"El Consejo Comarcal acogi\u00f3 la presentaci\u00f3n de la actividad. La capital de El Bierzo Alto ser\u00e1 el escenario de la primera jornada este s\u00e1bado 18 de marzo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T13:19:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-17T13:22:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os\",\"datePublished\":\"2023-03-17T13:19:55+00:00\",\"dateModified\":\"2023-03-17T13:22:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/\"},\"wordCount\":195,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/debutantes1.jpg\",\"keywords\":[\"Ponferrada\"],\"articleSection\":[\"Sin categorizar\",\"Social\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/\",\"name\":\"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/debutantes1.jpg\",\"datePublished\":\"2023-03-17T13:19:55+00:00\",\"dateModified\":\"2023-03-17T13:22:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/debutantes1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/debutantes1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/","og_locale":"gl_ES","og_type":"article","og_title":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo","og_description":"El Consejo Comarcal acogi\u00f3 la presentaci\u00f3n de la actividad. La capital de El Bierzo Alto ser\u00e1 el escenario de la primera jornada este s\u00e1bado 18 de marzo.","og_url":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2023-03-17T13:19:55+00:00","article_modified_time":"2023-03-17T13:22:31+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os","datePublished":"2023-03-17T13:19:55+00:00","dateModified":"2023-03-17T13:22:31+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/"},"wordCount":195,"image":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg","keywords":["Ponferrada"],"articleSection":["Sin categorizar","Social"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/","url":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/","name":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg","datePublished":"2023-03-17T13:19:55+00:00","dateModified":"2023-03-17T13:22:31+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/03\/debutantes1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/bembibre-ponferrada-y-vega-de-espinareda-acogen-la-liga-de-debutantes-de-futbol-en-la-que-participan-ninos-y-ninas-de-5-y-6-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Bembibre, Ponferrada y Vega de Espinareda acogen la Liga de Debutantes de f\u00fatbol en la que participan ni\u00f1os y ni\u00f1as de 5 y 6 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=130948"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/130949"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=130948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=130948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=130948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}