{"id":130716,"date":"2022-11-24T21:19:00","date_gmt":"2022-11-24T20:19:00","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=130716"},"modified":"2022-11-25T12:48:18","modified_gmt":"2022-11-25T11:48:18","slug":"el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/","title":{"rendered":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023"},"content":{"rendered":"\n<p>El presidente del Consejo Comarcal, Gerardo \u00c1lvarez Courel, y el alcalde de Ponferrada, Olegario Ram\u00f3n se reunieron este jueves en Madrid con responsables del <strong>Ministerio de Movilidad, Transportes y Agenda Urbana <\/strong>para conocer los planes del Gobierno con respecto a infraestructuras pendientes para El Bierzo. <\/p>\n\n\n\n<p>Uno de los primeros compromisos transmitidos fue la <strong>salida a informaci\u00f3n p\u00fablica del tramo de la A-76 entre Villamart\u00edn de la Abad\u00eda y Requejo<\/strong>, que,&nbsp;con un trazado de 6,2 km., discurre por los t\u00e9rminos municipales de Carracedelo, Toral de los Vados, Corull\u00f3n y Sobrado.&nbsp;<\/p>\n\n\n\n<p>Otro de los temas tratados fue la mejora de la <strong>conexi\u00f3n ferroviaria entre Le\u00f3n y Ponferrada<\/strong>. En este caso, los responsables del Ministerio aseguraron que se intentar\u00e1n agilizar los tr\u00e1mites para contratar el estudio de viabilidad para solucionar el nudo del Manzanal y acortar el tiempo del trayecto entre ambas ciudades.<\/p>\n\n\n\n<p>Los responsables del Ministerio informaron de la pr\u00f3xima licitaci\u00f3n, por valor de 11 millones de euros, de <strong>obras para reparar la A-6<\/strong> entre La Ba\u00f1eza y Astorga. El siguiente tramo que recibir\u00e1 inversiones ser\u00e1 el de Astorga-Ponferrada.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570-1024x684.jpeg\" alt=\"\" class=\"wp-image-130717\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570-980x551.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570-480x270.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es uno de los compromisos de la reuni\u00f3n que mantuvieron el presidente del Consejo y los alcaldes de Ponferrada y El Barco de Valdeorras con responsables del Ministerio de Movilidad, Transportes y Agenda Urbana.<\/p>\n","protected":false},"author":3,"featured_media":130717,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[414],"class_list":["post-130716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","tag-madrid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"Es uno de los compromisos de la reuni\u00f3n que mantuvieron el presidente del Consejo y los alcaldes de Ponferrada y El Barco de Valdeorras con responsables del Ministerio de Movilidad, Transportes y Agenda Urbana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T11:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023\",\"datePublished\":\"2022-11-24T20:19:00+00:00\",\"dateModified\":\"2022-11-25T11:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/\"},\"wordCount\":219,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/reunion-ministerio-movilidad-e1669375699570.jpeg\",\"keywords\":[\"Madrid\"],\"articleSection\":[\"Administraci\u00f3n\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/\",\"name\":\"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/reunion-ministerio-movilidad-e1669375699570.jpeg\",\"datePublished\":\"2022-11-24T20:19:00+00:00\",\"dateModified\":\"2022-11-25T11:48:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/reunion-ministerio-movilidad-e1669375699570.jpeg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/reunion-ministerio-movilidad-e1669375699570.jpeg\",\"width\":2000,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/","og_locale":"gl_ES","og_type":"article","og_title":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo","og_description":"Es uno de los compromisos de la reuni\u00f3n que mantuvieron el presidente del Consejo y los alcaldes de Ponferrada y El Barco de Valdeorras con responsables del Ministerio de Movilidad, Transportes y Agenda Urbana.","og_url":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2022-11-24T20:19:00+00:00","article_modified_time":"2022-11-25T11:48:18+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023","datePublished":"2022-11-24T20:19:00+00:00","dateModified":"2022-11-25T11:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/"},"wordCount":219,"image":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg","keywords":["Madrid"],"articleSection":["Administraci\u00f3n"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/","url":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/","name":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023 - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg","datePublished":"2022-11-24T20:19:00+00:00","dateModified":"2022-11-25T11:48:18+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/11\/reunion-ministerio-movilidad-e1669375699570.jpeg","width":2000,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-gobierno-sacara-a-informacion-publica-el-tramo-entre-villamartin-de-la-abadia-y-requejo-de-la-a-76-en-el-primer-trimestre-de-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El Gobierno sacar\u00e1 a informaci\u00f3n p\u00fablica el tramo entre Villamart\u00edn de la Abad\u00eda y Requejo de la A-76 en el primer trimestre de 2023"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=130716"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/130717"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=130716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=130716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=130716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}