{"id":130349,"date":"2022-06-27T20:44:00","date_gmt":"2022-06-27T18:44:00","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=130349"},"modified":"2022-06-28T10:19:57","modified_gmt":"2022-06-28T08:19:57","slug":"el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/","title":{"rendered":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o"},"content":{"rendered":"\n<p>La sede instituci\u00f3n comarcal acogi\u00f3 este lunes la reuni\u00f3n de trabajo entre el presidente de Consejo Comarcal, Gerardo \u00c1lvarez Courel, y el consejero de Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez Qui\u00f1ones, para tratar sobre <strong>el convenio de delegaci\u00f3n de competencias para la contrataci\u00f3n de brigadas y trabajos de prevenci\u00f3n de incendios<\/strong>, as\u00ed como asuntos relacionados con la Agrupaci\u00f3n Comarcal de Protecci\u00f3n Civil o la puesta en marcha del Parque Micol\u00f3gico. El encuentro ha contado con la asistencia de la delegada territorial de la Junta, Ester Mu\u00f1oz, y los consejeros comarcales de Protecci\u00f3n Civil y de Medio Ambiente, Vicente D\u00edaz y Ricardo Fern\u00e1ndez.<\/p>\n\n\n\n<p>En la reuni\u00f3n se tratado la posibilidad de revisar el importe que recibe el Consejo Comarcal para la <strong>contrataci\u00f3n de trabajos selv\u00edcolas<\/strong>, que permitiese incrementar los tiempos de trabajo de prevenci\u00f3n, as\u00ed como incrementar los tiempos de trabajo de las brigadas propias del Consejo Comarcal.<\/p>\n\n\n\n<p>Otra de las cuestiones tratadas es el incremento de la aportaci\u00f3n para el funcionamiento de la <strong>Agrupaci\u00f3n Comarcal de Protecci\u00f3n Civil<\/strong>, destinada fundamentalmente a sufragar los gastos de vigilancia del Camino de Santiago y ayuda al peregrino. El presidente del Consejo Comarcal ha mantenido que la actual colaboraci\u00f3n se invierte casi en su totalidad en las reparaciones del veh\u00edculo que utiliza la Agrupaci\u00f3n, que tiene 20 a\u00f1os de antig\u00fcedad. Por este motivo, tambi\u00e9n se ha solicitado la renovaci\u00f3n del citado veh\u00edculo.<\/p>\n\n\n\n<p>Por \u00faltimo, el presidente y el consejero han repasado los tr\u00e1mites pendientes para poder inscribir el <strong>Parque Micol\u00f3gico de El Bierzo<\/strong>, que pende de la definici\u00f3n de aspectos que pr\u00f3ximamente se concretar\u00e1n por parte del Consejo Comarcal. Tambi\u00e9n se ha solicitado apoyo econ\u00f3mico tras la puesta en marcha del mismo hasta que pueda financiarse con sus propios ingresos.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1-1024x683.jpg\" alt=\"\" class=\"wp-image-130350\" width=\"768\" height=\"512\"\/><figcaption>El Consejo Comarcal acogi\u00f3 este lunes la reuni\u00f3n para abordar una actualizaci\u00f3n en los convenios.<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La sede instituci\u00f3n comarcal acogi\u00f3 la reuni\u00f3n entre el presidente, Gerardo \u00c1lvarez Courel, y el consejero de Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez Qui\u00f1ones.<\/p>\n","protected":false},"author":3,"featured_media":130350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26,1],"tags":[294],"class_list":["post-130349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","category-sin-categorizar","tag-ponferrada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"La sede instituci\u00f3n comarcal acogi\u00f3 la reuni\u00f3n entre el presidente, Gerardo \u00c1lvarez Courel, y el consejero de Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez Qui\u00f1ones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T18:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-28T08:19:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o\",\"datePublished\":\"2022-06-27T18:44:00+00:00\",\"dateModified\":\"2022-06-28T08:19:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/\"},\"wordCount\":376,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/consejero1.jpg\",\"keywords\":[\"Ponferrada\"],\"articleSection\":[\"Administraci\u00f3n\",\"Sin categorizar\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/\",\"name\":\"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/consejero1.jpg\",\"datePublished\":\"2022-06-27T18:44:00+00:00\",\"dateModified\":\"2022-06-28T08:19:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/consejero1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/consejero1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/","og_locale":"gl_ES","og_type":"article","og_title":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo","og_description":"La sede instituci\u00f3n comarcal acogi\u00f3 la reuni\u00f3n entre el presidente, Gerardo \u00c1lvarez Courel, y el consejero de Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez Qui\u00f1ones.","og_url":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2022-06-27T18:44:00+00:00","article_modified_time":"2022-06-28T08:19:57+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o","datePublished":"2022-06-27T18:44:00+00:00","dateModified":"2022-06-28T08:19:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/"},"wordCount":376,"image":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg","keywords":["Ponferrada"],"articleSection":["Administraci\u00f3n","Sin categorizar"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/","url":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/","name":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg","datePublished":"2022-06-27T18:44:00+00:00","dateModified":"2022-06-28T08:19:57+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/consejero1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/el-presidente-comarcal-solicita-a-la-junta-un-incremento-en-las-aportaciones-de-medio-ambiente-para-mantener-a-las-brigadas-operativas-todo-el-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"El presidente comarcal solicita a la Junta un incremento en las aportaciones de Medio Ambiente para mantener a las brigadas operativas todo el a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=130349"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/130350"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=130349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=130349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=130349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}