{"id":130286,"date":"2022-06-02T16:39:00","date_gmt":"2022-06-02T14:39:00","guid":{"rendered":"https:\/\/ccbierzo.com\/?p=130286"},"modified":"2022-06-16T13:17:45","modified_gmt":"2022-06-16T11:17:45","slug":"jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo","status":"publish","type":"post","link":"https:\/\/ccbierzo.com\/gl\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/","title":{"rendered":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo"},"content":{"rendered":"\n<p>El carism\u00e1tico empresario se ha unido a la lista de <strong>hijos predilectos de El Bierzo<\/strong>, de la que ya forman parte el locutor Luis del Olmo, el poeta Juan Carlos Mestre y la halter\u00f3fila Lydia Valent\u00edn.  Al acto, celebrado este jueves, asisti\u00f3 una nutrida representaci\u00f3n de la sociedad berciana para rendir tributo a un &#8220;s\u00edmbolo de la comarca&#8221;, tal y como lo defini\u00f3 el presidente del Consejo Comarcal, Gerardo \u00c1lvarez Courel, en su intervenci\u00f3n. <\/p>\n\n\n\n<p>Durante el acto, el presidente comarcal realiz\u00f3 un recorrido por la trayectoria profesional y personal de Jos\u00e9 Luis Prada y lo describi\u00f3 como <strong>un apasionado de El Bierzo<\/strong>. &#8221; Lo demuestras cada d\u00eda, en cada iniciativa que emprendes y en cada idea que ronda por tu cabeza. Siempre, en tu cabeza y en tu coraz\u00f3n, prevalece el amor por esta comarca&#8221;.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00037-1024x683.jpeg\" alt=\"\" class=\"wp-image-130289\" width=\"512\" height=\"342\"\/><figcaption>Gerardo \u00c1lvarez Courel durante su intervenci\u00f3n.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Jos\u00e9 Luis Prada naci\u00f3 en Cacabelos en 1945. Con tan s\u00f3lo 15 a\u00f1os comenz\u00f3 a trabajar en el negocio familiar, una tienda que fue adquiriendo fama y en la que Prada comenz\u00f3 a vender conservas de cerezas en aguardiente. M\u00e1s adelante fue a\u00f1adiendo nuevos<strong> productos agroalimentarios t\u00edpicos de El Bierzo<\/strong> en su oferta y comenz\u00f3 su andadura dentro del mundo de la hosteler\u00eda con la apertura de La Moncloa. En los a\u00f1os 90 restaura y abre el Palacio de Canedo.<\/p>\n\n\n\n<p>En la actualidad, Jos\u00e9 Luis Prada preside la <strong><a href=\"https:\/\/pradaatope.com.es\/la-fundacion\/\">Fundaci\u00f3n Prada a Tope<\/a><\/strong>, que entre otras actividades convoca los Premios Palacio de Canedo para distinguir a los mejores trabajos de rehabilitaci\u00f3n de la arquitectura tradicional berciana. Tambi\u00e9n fue en dos ocasiones alcalde de Cacabelos y presidi\u00f3 el Consejo Regulador de la Denominaci\u00f3n de Origen Bierzo. Este a\u00f1o celebra el 50 aniversario de su marca comercial.<\/p>\n\n\n\n<p>Jos\u00e9 Luis Prada se mostr\u00f3 muy agradecido por el nombramiento como Hijo Predilecto, se emocion\u00f3 en su intervenci\u00f3n y aprovech\u00f3 para reivindicar la <strong>defensa del entorno natural de El Bierzo como la mejor fuente de riqueza y la m\u00e1s duradera<\/strong>. <\/p>\n\n\n\n<p>Jos\u00e9 Luis Prada recibi\u00f3 un diploma y una pieza de cristal, obra del artista Rogelio Pacios.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00049-1024x683.jpeg\" alt=\"\" class=\"wp-image-130291\" width=\"768\" height=\"512\"\/><figcaption>Jos\u00e9 Luis Prada recibe el titulo de Hijo Predilecto de El Bierzo.<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Galer\u00eda de im\u00e1genes<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" data-id=\"130295\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00050.jpeg\" alt=\"\" class=\"wp-image-130295\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00050.jpeg 1620w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00050-1280x853.jpeg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00050-980x653.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00050-480x320.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1620px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" data-id=\"130297\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00053.jpeg\" alt=\"\" class=\"wp-image-130297\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00053.jpeg 1620w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00053-1280x853.jpeg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00053-980x653.jpeg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/image00053-480x320.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1620px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130299\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA3.jpg\" alt=\"\" class=\"wp-image-130299\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA3.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA3-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA3-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA3-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130301\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA4.jpg\" alt=\"\" class=\"wp-image-130301\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA4.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA4-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA4-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA4-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130303\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada5.jpg\" alt=\"\" class=\"wp-image-130303\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada5.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada5-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada5-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada5-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130305\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada6.jpg\" alt=\"\" class=\"wp-image-130305\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada6.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada6-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada6-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada6-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130307\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada7.jpg\" alt=\"\" class=\"wp-image-130307\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada7.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada7-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada7-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada7-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" data-id=\"130309\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada8.jpg\" alt=\"\" class=\"wp-image-130309\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada8.jpg 1500w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada8-1280x853.jpg 1280w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada8-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/prada8-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1500px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"130316\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/hijo-predilecto-jose-luis-prada-web-1024x682.jpg\" alt=\"\" class=\"wp-image-130316\" srcset=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/hijo-predilecto-jose-luis-prada-web-980x653.jpg 980w, https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/hijo-predilecto-jose-luis-prada-web-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><a href=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/DISCURSO_PRADA_20220602-1.pdf\"><strong>Discurso del presidente del Consejo Comarcal del Bierzo<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El empresario estuvo arropado por su familia y una  amplia representaci\u00f3n de la sociedad berciana. Durante su intervenci\u00f3n, reivindic\u00f3 la defensa del entorno natural de la comarca como la mejor fuente de riqueza.<\/p>\n","protected":false},"author":3,"featured_media":130287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-130286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:description\" content=\"El empresario estuvo arropado por su familia y una amplia representaci\u00f3n de la sociedad berciana. Durante su intervenci\u00f3n, reivindic\u00f3 la defensa del entorno natural de la comarca como la mejor fuente de riqueza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T14:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-16T11:17:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Vidal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Vidal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/\"},\"author\":{\"name\":\"Marta Vidal\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"headline\":\"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo\",\"datePublished\":\"2022-06-02T14:39:00+00:00\",\"dateModified\":\"2022-06-16T11:17:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/\"},\"wordCount\":407,\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/PRADA1.jpg\",\"articleSection\":[\"Social\"],\"inLanguage\":\"gl-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/\",\"name\":\"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/PRADA1.jpg\",\"datePublished\":\"2022-06-02T14:39:00+00:00\",\"dateModified\":\"2022-06-16T11:17:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/PRADA1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/PRADA1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#\\\/schema\\\/person\\\/4e9a8395b397b1d4b8695a5274072278\",\"name\":\"Marta Vidal\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/","og_locale":"gl_ES","og_type":"article","og_title":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo","og_description":"El empresario estuvo arropado por su familia y una amplia representaci\u00f3n de la sociedad berciana. Durante su intervenci\u00f3n, reivindic\u00f3 la defensa del entorno natural de la comarca como la mejor fuente de riqueza.","og_url":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/","og_site_name":"Consejo Comarcal del Bierzo","article_published_time":"2022-06-02T14:39:00+00:00","article_modified_time":"2022-06-16T11:17:45+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg","type":"image\/jpeg"}],"author":"Marta Vidal","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Vidal","Tempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#article","isPartOf":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/"},"author":{"name":"Marta Vidal","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"headline":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo","datePublished":"2022-06-02T14:39:00+00:00","dateModified":"2022-06-16T11:17:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/"},"wordCount":407,"image":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg","articleSection":["Social"],"inLanguage":"gl-ES"},{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/","url":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/","name":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#primaryimage"},"image":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#primaryimage"},"thumbnailUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg","datePublished":"2022-06-02T14:39:00+00:00","dateModified":"2022-06-16T11:17:45+00:00","author":{"@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278"},"breadcrumb":{"@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#primaryimage","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg","contentUrl":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2022\/06\/PRADA1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/jose-luis-prada-recibe-el-titulo-de-hijo-predilecto-de-el-bierzo-en-un-emotivo-acto-celebrado-en-el-palacio-de-canedo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Luis Prada recibe el t\u00edtulo de Hijo Predilecto de El Bierzo en un emotivo acto celebrado en el Palacio de Canedo"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Person","@id":"https:\/\/ccbierzo.com\/gl\/#\/schema\/person\/4e9a8395b397b1d4b8695a5274072278","name":"Marta Vidal"}]}},"_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=130286"}],"version-history":[{"count":0,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/posts\/130286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/130287"}],"wp:attachment":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media?parent=130286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/categories?post=130286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/tags?post=130286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}