{"id":131848,"date":"2023-11-17T13:58:26","date_gmt":"2023-11-17T12:58:26","guid":{"rendered":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg"},"modified":"2023-11-17T13:58:26","modified_gmt":"2023-11-17T12:58:26","slug":"intur5-2-2","status":"inherit","type":"attachment","link":"https:\/\/ccbierzo.com\/gl\/intur5-2-2\/","title":{"rendered":"intur5"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-131848","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>intur5 - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"intur5 - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur5.jpg\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur5.jpg\",\"name\":\"intur5 - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"datePublished\":\"2023-11-17T12:58:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur5.jpg#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur5.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/intur5.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"intur5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"intur5 - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","og_locale":"gl_ES","og_type":"article","og_title":"intur5 - Consejo Comarcal del Bierzo","og_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","og_site_name":"Consejo Comarcal del Bierzo","og_image":[{"width":1500,"height":1000,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","name":"intur5 - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"datePublished":"2023-11-17T12:58:26+00:00","breadcrumb":{"@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"intur5"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1000,"file":"2023\/11\/intur5.jpg","filesize":1158286,"sizes":{"medium":{"file":"intur5-300x200.jpg","width":300,"height":200,"filesize":23256,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-300x200.jpg"},"large":{"file":"intur5-1024x683.jpg","width":1024,"height":683,"filesize":164775,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1024x683.jpg"},"thumbnail":{"file":"intur5-150x150.jpg","width":150,"height":150,"filesize":10167,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-150x150.jpg"},"medium_large":{"file":"intur5-768x512.jpg","width":768,"height":512,"filesize":103569,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-768x512.jpg"},"et-pb-post-main-image":{"file":"intur5-400x250.jpg","width":400,"height":250,"filesize":34473,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"intur5-1080x675.jpg","width":1080,"height":675,"filesize":167996,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1080x675.jpg"},"et-pb-portfolio-image":{"file":"intur5-400x284.jpg","width":400,"height":284,"filesize":38543,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"intur5-510x382.jpg","width":510,"height":382,"filesize":59287,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"intur5-1080x720.jpg","width":1080,"height":720,"filesize":178009,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1080x720.jpg"},"et-pb-gallery-module-image-portrait":{"file":"intur5-400x516.jpg","width":400,"height":516,"filesize":53807,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-400x516.jpg"},"et-pb-image--responsive--desktop":{"file":"intur5-1280x853.jpg","width":1280,"height":853,"filesize":232158,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1280x853.jpg"},"et-pb-image--responsive--tablet":{"file":"intur5-980x653.jpg","width":980,"height":653,"filesize":153900,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-980x653.jpg"},"et-pb-image--responsive--phone":{"file":"intur5-480x320.jpg","width":480,"height":320,"filesize":48944,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-480x320.jpg"},"extra-image-huge":{"file":"intur5-1280x768.jpg","width":1280,"height":768,"filesize":207772,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1280x768.jpg"},"extra-image-single-post":{"file":"intur5-1280x640.jpg","width":1280,"height":640,"filesize":176373,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-1280x640.jpg"},"extra-image-medium":{"file":"intur5-627x376.jpg","width":627,"height":376,"filesize":67572,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-627x376.jpg"},"extra-image-small":{"file":"intur5-440x264.jpg","width":440,"height":264,"filesize":38026,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-440x264.jpg"},"extra-image-square-medium":{"file":"intur5-440x440.jpg","width":440,"height":440,"filesize":53885,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-440x440.jpg"},"extra-image-square-small":{"file":"intur5-150x150.jpg","width":150,"height":150,"filesize":10167,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5-150x150.jpg"},"full":{"file":"intur5.jpg","width":1500,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/intur5.jpg","_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/131848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=131848"}]}}