{"id":131834,"date":"2023-11-15T14:51:43","date_gmt":"2023-11-15T13:51:43","guid":{"rendered":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3.jpg"},"modified":"2023-11-15T14:51:43","modified_gmt":"2023-11-15T13:51:43","slug":"carucedo3-3","status":"inherit","type":"attachment","link":"https:\/\/ccbierzo.com\/gl\/carucedo3-3\/","title":{"rendered":"carucedo3"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-131834","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>carucedo3 - Consejo Comarcal del Bierzo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carucedo3 - Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Consejo Comarcal del Bierzo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/carucedo3-scaled.jpg\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/carucedo3-scaled.jpg\",\"name\":\"carucedo3 - Consejo Comarcal del Bierzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\"},\"datePublished\":\"2023-11-15T13:51:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/carucedo3-scaled.jpg#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/carucedo3-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/carucedo3-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"carucedo3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/\",\"name\":\"Consejo Comarcal del Bierzo\",\"description\":\"P\u00e1gina Oficial del Consejo Comarcal del Bierzo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccbierzo.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"carucedo3 - Consejo Comarcal del Bierzo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","og_locale":"gl_ES","og_type":"article","og_title":"carucedo3 - Consejo Comarcal del Bierzo","og_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","og_site_name":"Consejo Comarcal del Bierzo","og_image":[{"width":2560,"height":1920,"url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","name":"carucedo3 - Consejo Comarcal del Bierzo","isPartOf":{"@id":"https:\/\/ccbierzo.com\/gl\/#website"},"datePublished":"2023-11-15T13:51:43+00:00","breadcrumb":{"@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ccbierzo.com\/gl\/"},{"@type":"ListItem","position":2,"name":"carucedo3"}]},{"@type":"WebSite","@id":"https:\/\/ccbierzo.com\/gl\/#website","url":"https:\/\/ccbierzo.com\/gl\/","name":"Consejo Comarcal del Bierzo","description":"P\u00e1gina Oficial del Consejo Comarcal del Bierzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccbierzo.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"2023\/11\/carucedo3-scaled.jpg","filesize":530832,"sizes":{"medium":{"file":"carucedo3-300x225.jpg","width":300,"height":225,"filesize":45813,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-300x225.jpg"},"large":{"file":"carucedo3-1024x768.jpg","width":1024,"height":768,"filesize":143277,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1024x768.jpg"},"thumbnail":{"file":"carucedo3-150x150.jpg","width":150,"height":150,"filesize":37372,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-150x150.jpg"},"medium_large":{"file":"carucedo3-768x576.jpg","width":768,"height":576,"filesize":100263,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-768x576.jpg"},"1536x1536":{"file":"carucedo3-1536x1152.jpg","width":1536,"height":1152,"filesize":248973,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1536x1152.jpg"},"2048x2048":{"file":"carucedo3-2048x1536.jpg","width":2048,"height":1536,"filesize":379506,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-2048x1536.jpg"},"et-pb-post-main-image":{"file":"carucedo3-400x250.jpg","width":400,"height":250,"filesize":52652,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"carucedo3-1080x675.jpg","width":1080,"height":675,"filesize":143692,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1080x675.jpg"},"et-pb-portfolio-image":{"file":"carucedo3-400x284.jpg","width":400,"height":284,"filesize":53858,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"carucedo3-510x382.jpg","width":510,"height":382,"filesize":65883,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"carucedo3-1080x810.jpg","width":1080,"height":810,"filesize":154024,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1080x810.jpg"},"et-pb-gallery-module-image-portrait":{"file":"carucedo3-400x516.jpg","width":400,"height":516,"filesize":69516,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-400x516.jpg"},"et-pb-post-main-image-fullwidth-large":{"file":"carucedo3-2880x1800.jpg","width":2880,"height":1800,"filesize":578368,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-2880x1800.jpg"},"et-pb-image--responsive--desktop":{"file":"carucedo3-1280x960.jpg","width":1280,"height":960,"filesize":193442,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1280x960.jpg"},"et-pb-image--responsive--tablet":{"file":"carucedo3-980x735.jpg","width":980,"height":735,"filesize":135682,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-980x735.jpg"},"et-pb-image--responsive--phone":{"file":"carucedo3-480x360.jpg","width":480,"height":360,"filesize":62527,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-480x360.jpg"},"extra-image-huge":{"file":"carucedo3-1280x768.jpg","width":1280,"height":768,"filesize":176020,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1280x768.jpg"},"extra-image-single-post":{"file":"carucedo3-1280x640.jpg","width":1280,"height":640,"filesize":160610,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-1280x640.jpg"},"extra-image-medium":{"file":"carucedo3-627x376.jpg","width":627,"height":376,"filesize":75621,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-627x376.jpg"},"extra-image-small":{"file":"carucedo3-440x264.jpg","width":440,"height":264,"filesize":55729,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-440x264.jpg"},"extra-image-square-medium":{"file":"carucedo3-440x440.jpg","width":440,"height":440,"filesize":66784,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-440x440.jpg"},"extra-image-square-small":{"file":"carucedo3-150x150.jpg","width":150,"height":150,"filesize":37372,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-150x150.jpg"},"full":{"file":"carucedo3-scaled.jpg","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg"}},"image_meta":{"aperture":"1.89","credit":"","camera":"2201117SY","caption":"","created_timestamp":"1700049089","copyright":"","focal_length":"5.89","iso":"1025","shutter_speed":"0.029994","title":"","orientation":"1","keywords":[]},"original_image":"carucedo3.jpg"},"post":null,"source_url":"https:\/\/ccbierzo.com\/wp-content\/uploads\/2023\/11\/carucedo3-scaled.jpg","_links":{"self":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media\/131834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ccbierzo.com\/gl\/wp-json\/wp\/v2\/comments?post=131834"}]}}